{"id":4791,"date":"2023-07-04T11:48:40","date_gmt":"2023-07-04T09:48:40","guid":{"rendered":"https:\/\/edi-service.partners\/stampa\/"},"modified":"2025-03-07T19:26:25","modified_gmt":"2025-03-07T17:26:25","slug":"stampa","status":"publish","type":"page","link":"https:\/\/edi-service.partners\/it\/stampa\/","title":{"rendered":"Stampa"},"content":{"rendered":"\n<p>Benvenuto nella sezione Relazioni Pubbliche, la sezione di servizio per giornalisti e opinionisti. Qui troverai comunicati stampa, loghi, grafici e immagini attuali. <\/p>\n\n<p>Se non riesci a trovare le informazioni che stai cercando, se hai ulteriori domande o se vuoi contattarci per interviste e ricerche dirette, invia un&#8217;e-mail a <a href=\"mailto:marketing@avenum.com\" target=\"_blank\" rel=\"noreferrer noopener\">marketing@avenum.com<\/a>.<\/p>\n\n<p><em>Nota:<\/em> l&#8217;uso editoriale dei testi \u00e8 gratuito solo se vengono citati Avenum o Avedium. Qualsiasi altro utilizzo, compresi gli estratti, \u00e8 consentito solo previo consenso. <\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/edi-service.partners\/it\/stampa\/scarica-i-loghi\/\">Scarica i loghi<\/a><\/div>\n\n\n\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/edi-service.partners\/it\/stampa\/scarica-le-immagini\/\">Scarica le immagini<\/a><\/div>\n<\/div>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"409\" data-id=\"372\" src=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-1024x409.jpeg\" alt=\"\" class=\"wp-image-372\" srcset=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-1024x409.jpeg 1024w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-300x120.jpeg 300w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-768x307.jpeg 768w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-1536x614.jpeg 1536w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/mega-2048x818.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"105\" src=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-1024x681.jpg\" alt=\"mega\" class=\"wp-image-105\" srcset=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-1024x681.jpg 1024w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-300x200.jpg 300w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-768x511.jpg 768w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-1536x1022.jpg 1536w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/mega-2048x1362.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"224\" src=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/ds-she-1024x681.jpeg\" alt=\"ds-she\" class=\"wp-image-224\" srcset=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/ds-she-1024x681.jpeg 1024w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/ds-she-300x200.jpeg 300w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/ds-she-768x511.jpeg 768w, https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/ds-she.jpeg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Benvenuto nella sezione Relazioni Pubbliche, la sezione di servizio per giornalisti e opinionisti. Qui troverai comunicati stampa, loghi, grafici e immagini attuali. Se non riesci a trovare le informazioni che stai cercando, se hai ulteriori domande o se vuoi contattarci per interviste e ricerche dirette, invia un&#8217;e-mail a marketing@avenum.com. Nota: l&#8217;uso editoriale dei testi \u00e8 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4792,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"slim_seo":{"title":"Stampa","description":"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull'azienda."},"footnotes":""},"folder":[9],"class_list":["post-4791","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stampa - EDI Service Partners<\/title>\n<meta name=\"description\" content=\"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull&#039;azienda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edi-service.partners\/it\/stampa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stampa - EDI Service Partners\" \/>\n<meta property=\"og:description\" content=\"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull&#039;azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edi-service.partners\/it\/stampa\/\" \/>\n<meta property=\"og:site_name\" content=\"EDI Service Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ediservicepartners\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/\",\"url\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/\",\"name\":\"Stampa - EDI Service Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edi-service.partners\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg\",\"datePublished\":\"2023-07-04T09:48:40+00:00\",\"dateModified\":\"2025-03-07T17:26:25+00:00\",\"description\":\"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull'azienda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edi-service.partners\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg\",\"contentUrl\":\"https:\\\/\\\/edi-service.partners\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg\",\"width\":768,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/stampa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/\",\"name\":\"EDI Service Partners\",\"description\":\"Ihre Partner f\u00fcr EDI-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#organization\",\"name\":\"Avenum Technologie GmbH und Avedium Technologie GmbH\",\"url\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edi-service.partners\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/edi-service.png\",\"contentUrl\":\"https:\\\/\\\/edi-service.partners\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/edi-service.png\",\"width\":1580,\"height\":250,\"caption\":\"Avenum Technologie GmbH und Avedium Technologie GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/edi-service.partners\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ediservicepartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ediservice\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stampa - EDI Service Partners","description":"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull'azienda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edi-service.partners\/it\/stampa\/","og_locale":"it_IT","og_type":"article","og_title":"Stampa - EDI Service Partners","og_description":"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull'azienda.","og_url":"https:\/\/edi-service.partners\/it\/stampa\/","og_site_name":"EDI Service Partners","article_publisher":"https:\/\/www.facebook.com\/ediservicepartners","article_modified_time":"2025-03-07T17:26:25+00:00","og_image":[{"width":768,"height":510,"url":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edi-service.partners\/it\/stampa\/","url":"https:\/\/edi-service.partners\/it\/stampa\/","name":"Stampa - EDI Service Partners","isPartOf":{"@id":"https:\/\/edi-service.partners\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edi-service.partners\/it\/stampa\/#primaryimage"},"image":{"@id":"https:\/\/edi-service.partners\/it\/stampa\/#primaryimage"},"thumbnailUrl":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg","datePublished":"2023-07-04T09:48:40+00:00","dateModified":"2025-03-07T17:26:25+00:00","description":"Vuoi fare un reportage su Avenum e Avedium? Qui troverai i contatti stampa, le foto stampa e le informazioni sull'azienda.","breadcrumb":{"@id":"https:\/\/edi-service.partners\/it\/stampa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edi-service.partners\/it\/stampa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/edi-service.partners\/it\/stampa\/#primaryimage","url":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg","contentUrl":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/06\/27d9bfbb-ee68-4286-8605-64b7f5cf4900.jpeg","width":768,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/edi-service.partners\/it\/stampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/edi-service.partners\/it\/"},{"@type":"ListItem","position":2,"name":"Stampa"}]},{"@type":"WebSite","@id":"https:\/\/edi-service.partners\/it\/#website","url":"https:\/\/edi-service.partners\/it\/","name":"EDI Service Partners","description":"Ihre Partner f\u00fcr EDI-L\u00f6sungen","publisher":{"@id":"https:\/\/edi-service.partners\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edi-service.partners\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/edi-service.partners\/it\/#organization","name":"Avenum Technologie GmbH und Avedium Technologie GmbH","url":"https:\/\/edi-service.partners\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/edi-service.partners\/it\/#\/schema\/logo\/image\/","url":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/edi-service.png","contentUrl":"https:\/\/edi-service.partners\/wp-content\/uploads\/2023\/05\/edi-service.png","width":1580,"height":250,"caption":"Avenum Technologie GmbH und Avedium Technologie GmbH"},"image":{"@id":"https:\/\/edi-service.partners\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ediservicepartners","https:\/\/www.linkedin.com\/company\/ediservice"]}]}},"_links":{"self":[{"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/pages\/4791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/comments?post=4791"}],"version-history":[{"count":1,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/pages\/4791\/revisions"}],"predecessor-version":[{"id":4793,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/pages\/4791\/revisions\/4793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/media\/4792"}],"wp:attachment":[{"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/media?parent=4791"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/edi-service.partners\/it\/wp-json\/wp\/v2\/folder?post=4791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}